{"id":252,"count":2,"description":"","link":"https:\/\/www.homebelike.com\/blog\/category\/vacation-rental\/colombia-vacation-rental\/","name":"colombia vacation rental","slug":"colombia-vacation-rental","taxonomy":"category","parent":250,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>colombia vacation rental Archives | HomeBeLike<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.homebelike.com\/blog\/category\/vacation-rental\/colombia-vacation-rental\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"colombia vacation rental Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.homebelike.com\/blog\/category\/vacation-rental\/colombia-vacation-rental\/\" \/>\n<meta property=\"og:site_name\" content=\"HomeBeLike\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.homebelike.com\/wordpress\/wp-content\/uploads\/2023\/12\/02134852\/cropped-hbl-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/category\\\/vacation-rental\\\/colombia-vacation-rental\\\/\",\"url\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/category\\\/vacation-rental\\\/colombia-vacation-rental\\\/\",\"name\":\"colombia vacation rental Archives | HomeBeLike\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/category\\\/vacation-rental\\\/colombia-vacation-rental\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/category\\\/vacation-rental\\\/colombia-vacation-rental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"vacation rental\",\"item\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/category\\\/vacation-rental\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"colombia vacation rental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/\",\"name\":\"Homebelike\",\"description\":\"Be our guest, Feel like  home\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/#organization\"},\"alternateName\":\"Homebelike\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/#organization\",\"name\":\"Homebelike\",\"alternateName\":\"Homebelike\",\"url\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn.homebelike.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/06161529\\\/hbl-logo.png\",\"contentUrl\":\"https:\\\/\\\/cdn.homebelike.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/06161529\\\/hbl-logo.png\",\"width\":416,\"height\":100,\"caption\":\"Homebelike\"},\"image\":{\"@id\":\"https:\\\/\\\/www.homebelike.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/homebelike.rentals\",\"https:\\\/\\\/www.instagram.com\\\/homebelike.rentals\\\/\"],\"description\":\"A new vacation rental home company, Homebelike, has launched within the Dominican Republic and will soon be introduced in Panama and Mexico, as well.\",\"legalName\":\"Homebelike\",\"foundingDate\":\"2024-07-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"colombia vacation rental Archives | HomeBeLike","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.homebelike.com\/blog\/category\/vacation-rental\/colombia-vacation-rental\/","og_locale":"en_US","og_type":"article","og_title":"colombia vacation rental Archives","og_url":"https:\/\/www.homebelike.com\/blog\/category\/vacation-rental\/colombia-vacation-rental\/","og_site_name":"HomeBeLike","og_image":[{"width":512,"height":512,"url":"https:\/\/cdn.homebelike.com\/wordpress\/wp-content\/uploads\/2023\/12\/02134852\/cropped-hbl-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.homebelike.com\/blog\/category\/vacation-rental\/colombia-vacation-rental\/","url":"https:\/\/www.homebelike.com\/blog\/category\/vacation-rental\/colombia-vacation-rental\/","name":"colombia vacation rental Archives | HomeBeLike","isPartOf":{"@id":"https:\/\/www.homebelike.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.homebelike.com\/blog\/category\/vacation-rental\/colombia-vacation-rental\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.homebelike.com\/blog\/category\/vacation-rental\/colombia-vacation-rental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.homebelike.com\/blog\/"},{"@type":"ListItem","position":2,"name":"vacation rental","item":"https:\/\/www.homebelike.com\/blog\/category\/vacation-rental\/"},{"@type":"ListItem","position":3,"name":"colombia vacation rental"}]},{"@type":"WebSite","@id":"https:\/\/www.homebelike.com\/blog\/#website","url":"https:\/\/www.homebelike.com\/blog\/","name":"Homebelike","description":"Be our guest, Feel like  home","publisher":{"@id":"https:\/\/www.homebelike.com\/blog\/#organization"},"alternateName":"Homebelike","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.homebelike.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.homebelike.com\/blog\/#organization","name":"Homebelike","alternateName":"Homebelike","url":"https:\/\/www.homebelike.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.homebelike.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.homebelike.com\/wordpress\/wp-content\/uploads\/2023\/12\/06161529\/hbl-logo.png","contentUrl":"https:\/\/cdn.homebelike.com\/wordpress\/wp-content\/uploads\/2023\/12\/06161529\/hbl-logo.png","width":416,"height":100,"caption":"Homebelike"},"image":{"@id":"https:\/\/www.homebelike.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/homebelike.rentals","https:\/\/www.instagram.com\/homebelike.rentals\/"],"description":"A new vacation rental home company, Homebelike, has launched within the Dominican Republic and will soon be introduced in Panama and Mexico, as well.","legalName":"Homebelike","foundingDate":"2024-07-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"_links":{"self":[{"href":"https:\/\/www.homebelike.com\/blog\/wp-json\/wp\/v2\/categories\/252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.homebelike.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.homebelike.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.homebelike.com\/blog\/wp-json\/wp\/v2\/categories\/250"}],"wp:post_type":[{"href":"https:\/\/www.homebelike.com\/blog\/wp-json\/wp\/v2\/posts?categories=252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}